{"id":5,"count":98,"description":"","link":"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/","name":"Salud","slug":"salud","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salud - Blog OficinaEmpleo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud - Blog OficinaEmpleo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias y consejos de empleo | Blog OficinaEmpleo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OficinaEmpleo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/\",\"name\":\"Salud - Blog OficinaEmpleo\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oficinaempleo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"name\":\"Noticias y Consejos de Empleo | Blog OficinaEmpleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\",\"name\":\"OficinaEmpleo\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"width\":478,\"height\":57,\"caption\":\"OficinaEmpleo\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/OficinaEmpleo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud - Blog OficinaEmpleo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/","og_locale":"es_ES","og_type":"article","og_title":"Salud - Blog OficinaEmpleo","og_url":"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/","og_site_name":"Noticias y consejos de empleo | Blog OficinaEmpleo","twitter_card":"summary_large_image","twitter_site":"@OficinaEmpleo","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/","url":"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/","name":"Salud - Blog OficinaEmpleo","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.oficinaempleo.com\/blog\/category\/salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oficinaempleo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Salud"}]},{"@type":"WebSite","@id":"https:\/\/www.oficinaempleo.com\/blog\/#website","url":"https:\/\/www.oficinaempleo.com\/blog\/","name":"Noticias y Consejos de Empleo | Blog OficinaEmpleo","description":"","publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization","name":"OficinaEmpleo","url":"https:\/\/www.oficinaempleo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","width":478,"height":57,"caption":"OficinaEmpleo"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/OficinaEmpleo"]}]}},"_links":{"self":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}