{"id":16455,"date":"2016-12-09T01:17:35","date_gmt":"2016-12-08T23:17:35","guid":{"rendered":"https:\/\/www.oficinaempleo.com\/blog\/?p=16455"},"modified":"2016-12-09T10:24:12","modified_gmt":"2016-12-09T08:24:12","slug":"diferentes-tipos-entrevista-trabajo-te-pueden","status":"publish","type":"post","link":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/","title":{"rendered":"Diferentes tipos de entrevista de trabajo que te pueden hacer"},"content":{"rendered":"<div class=\"su-button-center\"><a href=\"https:\/\/jobs.oficinaempleo.com\/registro?origen=ORG-web&#038;utm_source=OE&#038;utm_medium=boton_registro&#038;utm_content=homepage&#038;utm_campaign=organic\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#ec7d0c;border-color:#bd640a;border-radius:10px\" target=\"__blank\"><span style=\"color:#FFFFFF;padding:8px 26px;font-size:20px;line-height:30px;border-color:#f2a455;border-radius:10px;text-shadow:none\"><i class=\"sui sui-arrow-circle-right\" style=\"font-size:20px;color:#FFFFFF\"><\/i> Reg\u00edstrate gratis en OficinaEmpleo<\/span><\/a><\/div>Cuando buscamos ofertas de trabajo, ya sea porque estamos en <a href=\"https:\/\/www.sepe.es\/\"><strong>situaci\u00f3n de desempleo<\/strong><\/a> o porque queremos cambiarnos de trabajo, y enviamos nuestro curr\u00edculum a las empresas -no te pierdas estos <a href=\"https:\/\/www.oficinaempleo.com\/blog\/10-trucos-para-parecer-mejor-de-lo-que-eres-en-tu-curriculum\/\"><strong>trucos para parecer mejor de lo que eres en tu curr\u00edculum<\/strong><\/a>\u00a0que te facilitamos en <strong>OficinaEmpleo<\/strong>-, el primer gran objetivo que tenemos es conseguir una entrevista de trabajo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16456 size-full\" src=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg\" alt=\"Diferentes tipos de entrevista de trabajo que te pueden hacer\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista-300x160.jpg 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p>Despu\u00e9s, si nuestro perfil profesional se ajusta al perfil que busca la empresa para el puesto demandado y causamos una buena imagen en la entrevista, estaremos en condiciones de lograr el objetivo final, que es conseguir el trabajo. Como os hemos contado en otras ocasiones en <strong>OficinaEmpleo<\/strong>, las entrevistas de trabajo requieren una preparaci\u00f3n previa por nuestra parte -en este otro art\u00edculo te\u00a0damos <a href=\"https:\/\/www.oficinaempleo.com\/blog\/5-claves-para-destacar-en-una-entrevista-de-trabajo\/\"><strong>5 claves para\u00a0destacar\u00a0en una entrevista de trabajo<\/strong><\/a>&#8211; para hacer todo cuanto est\u00e9 en nuestra mano para conseguir el empleo. Por eso, a continuaci\u00f3n repasamos los <strong>diferentes tipos de entrevista de trabajo que te pueden hacer<\/strong>.<\/p>\n<p>En primer lugar existe una <strong>clasificaci\u00f3n de entrevistas de trabajo<\/strong> en funci\u00f3n del n\u00famero de personas que participan simult\u00e1neamente en la entrevista. Desde el punto de vista de los candidatos, la entrevista de trabajo puede ser <strong>individual<\/strong>, si s\u00f3lo participamos nosotros, <strong>o de grupo<\/strong>, cuando son varias las personas entrevistadas.<\/p>\n<p>Y desde el punto de vista de los entrevistadores, la entrevista puede ser <strong>individual<\/strong>, cuando nos entrevista una \u00fanica persona; <strong>de panel<\/strong>, cuando varios reclutadores de personal nos entrevistan a la vez; <strong>o en l\u00ednea<\/strong>, cuando los candidatos se van entrevistando con personas de diferentes \u00e1reas o categor\u00edas profesionales.<\/p>\n<p>Si nos fijamos en el contenido, las entrevistas de trabajo pueden ser <strong>estructuradas<\/strong>, cuando el entrevistador sigue un esquema predeterminado de preguntas; <strong>libres<\/strong>, cuando no sigue un esquema fijo; o <strong>semiestructuradas<\/strong>, cuando se produce una mezcla de las dos anteriores.<\/p>\n<p>Adem\u00e1s, si nos fijamos en el contenido, tambi\u00e9n tendr\u00edamos que incluir en esta clasificaci\u00f3n a las <strong>entrevistas \u201cmillennials\u201d<\/strong> que realizan grandes compa\u00f1\u00edas como Google, Apple, Facebook, Amazon o Yahoo y en las que los candidatos deben responder curiosas preguntas que van m\u00e1s all\u00e1 de las relacionadas con la experiencia, la formaci\u00f3n o las capacidades profesionales de los aspirantes.<\/p>\n<p>Algunas de esas preguntas siguen el esquema de un problema matem\u00e1tico -por ejemplo, \u00bfcu\u00e1ntas veces se superponen las agujas del reloj en un d\u00eda?-, pero otras son m\u00e1s abiertas y sorprendentes, como \u201c\u00bfcu\u00e1nto cobrar\u00edas por limpiar todas las ventanas de Seattle?\u201d.<\/p>\n<p>Tambi\u00e9n existe una clasificaci\u00f3n de <strong>entrevistas de trabajo<\/strong> en funci\u00f3n del medio utilizado. Lo m\u00e1s normal es que una entrevista de trabajo se realice de forma presencial, pero cada vez es m\u00e1s frecuente que se hagan <strong>por tel\u00e9fono o por videollamada<\/strong> a trav\u00e9s de aplicaciones como <a href=\"https:\/\/www.skype.com\/es\/\"><strong>Skype<\/strong><\/a> cuando el candidato reside en otra ciudad o incluso en otro pa\u00eds. Incluso, en alg\u00fan caso la entrevista de trabajo, sobre todo en la primera fase de los <strong>procesos de selecci\u00f3n<\/strong>, puede realizarse por otros medios como el correo electr\u00f3nico.<\/p>\n<p>Recuerda que, aunque no sea una entrevista de trabajo como tal, tambi\u00e9n es probable \u2013de hecho, cada vez m\u00e1s- que te encuentres con una <strong>din\u00e1mica de grupo<\/strong> dentro del proceso de selecci\u00f3n de personal. En las din\u00e1micas de grupo se suele plantear una o varias situaciones concretas, que no tienen por qu\u00e9 estar relacionadas con el trabajo, a dos o m\u00e1s equipos de candidatos para que alcancen puntos en com\u00fan.<\/p>\n<p>En estos casos, los reclutadores de personal se fijan en la actitud de los aspirantes para evaluar aspectos como sus dotes de liderazgo, su capacidad para trabajar en equipo, su iniciativa o su creatividad.<\/p>\n<div class=\"su-button-center\"><a href=\"https:\/\/jobs.oficinaempleo.com\/registro?origen=ORG-web&#038;utm_source=OE&#038;utm_medium=boton_registro&#038;utm_content=homepage&#038;utm_campaign=organic\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#ec7d0c;border-color:#bd640a;border-radius:10px\" target=\"__blank\"><span style=\"color:#FFFFFF;padding:8px 26px;font-size:20px;line-height:30px;border-color:#f2a455;border-radius:10px;text-shadow:none\"><i class=\"sui sui-arrow-circle-right\" style=\"font-size:20px;color:#FFFFFF\"><\/i> Reg\u00edstrate gratis en OficinaEmpleo<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfConoces todas estas clases de entrevista de trabajo que pueden hacerte?<\/p>\n","protected":false},"author":2,"featured_media":16456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[192,4502,597,4501,826,4313],"class_list":["post-16455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos-humanos","tag-entrevista-de-trabajo","tag-entrevista-de-trabajo-por-skype","tag-preguntas-en-una-entrevista-de-trabajo","tag-procesos-de-seleccion","tag-seleccion-de-personal","tag-tipos-de-entrevista-de-trabajo","cat-11-id","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diferentes tipos de entrevista de trabajo que te pueden hacer<\/title>\n<meta name=\"description\" content=\"\u00bfTienes una entrevista de trabajo? \u00bfNo sabes a lo que te vas a enfrentar? A continuaci\u00f3n te desglosamos los tipos de entrevista que te pueden hacer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diferentes tipos de entrevista de trabajo que te pueden hacer\" \/>\n<meta property=\"og:description\" content=\"\u00bfTienes una entrevista de trabajo? \u00bfNo sabes a lo que te vas a enfrentar? A continuaci\u00f3n te desglosamos los tipos de entrevista que te pueden hacer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias y consejos de empleo | Blog OficinaEmpleo\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/OficinaEmpleo\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-08T23:17:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-09T08:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OficinaEmpleo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:site\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"OficinaEmpleo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/\"},\"author\":{\"name\":\"OficinaEmpleo\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114\"},\"headline\":\"Diferentes tipos de entrevista de trabajo que te pueden hacer\",\"datePublished\":\"2016-12-08T23:17:35+00:00\",\"dateModified\":\"2016-12-09T08:24:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/\"},\"wordCount\":738,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg\",\"keywords\":[\"entrevista de trabajo\",\"entrevista de trabajo por Skype\",\"preguntas en una entrevista de trabajo\",\"procesos de selecci\u00f3n\",\"selecci\u00f3n de personal\",\"tipos de entrevista de trabajo\"],\"articleSection\":[\"Recursos humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/\",\"name\":\"Diferentes tipos de entrevista de trabajo que te pueden hacer\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg\",\"datePublished\":\"2016-12-08T23:17:35+00:00\",\"dateModified\":\"2016-12-09T08:24:12+00:00\",\"description\":\"\u00bfTienes una entrevista de trabajo? \u00bfNo sabes a lo que te vas a enfrentar? A continuaci\u00f3n te desglosamos los tipos de entrevista que te pueden hacer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg\",\"width\":590,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oficinaempleo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diferentes tipos de entrevista de trabajo que te pueden hacer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"name\":\"Noticias y Consejos de Empleo | Blog OficinaEmpleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\",\"name\":\"OficinaEmpleo\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"width\":478,\"height\":57,\"caption\":\"OficinaEmpleo\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/OficinaEmpleo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114\",\"name\":\"OficinaEmpleo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g\",\"caption\":\"OficinaEmpleo\"},\"description\":\"En OficinaEmpleo queremos ayudarte a conseguir trabajo. Por eso, adem\u00e1s de ofrecerte ofertas de empleo en nuestro portal, te ense\u00f1amos las novedades del sector, y consejos para mejorar tu perfil.\",\"sameAs\":[\"http:\/\/www.oficinaempleo.com\/\",\"https:\/\/www.facebook.com\/OficinaEmpleo\",\"https:\/\/x.com\/OficinaEmpleo\"],\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/author\/empleo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diferentes tipos de entrevista de trabajo que te pueden hacer","description":"\u00bfTienes una entrevista de trabajo? \u00bfNo sabes a lo que te vas a enfrentar? A continuaci\u00f3n te desglosamos los tipos de entrevista que te pueden hacer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/","og_locale":"es_ES","og_type":"article","og_title":"Diferentes tipos de entrevista de trabajo que te pueden hacer","og_description":"\u00bfTienes una entrevista de trabajo? \u00bfNo sabes a lo que te vas a enfrentar? A continuaci\u00f3n te desglosamos los tipos de entrevista que te pueden hacer.","og_url":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/","og_site_name":"Noticias y consejos de empleo | Blog OficinaEmpleo","article_author":"https:\/\/www.facebook.com\/OficinaEmpleo","article_published_time":"2016-12-08T23:17:35+00:00","article_modified_time":"2016-12-09T08:24:12+00:00","og_image":[{"width":590,"height":315,"url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg","type":"image\/jpeg"}],"author":"OficinaEmpleo","twitter_card":"summary_large_image","twitter_creator":"@OficinaEmpleo","twitter_site":"@OficinaEmpleo","twitter_misc":{"Written by":"OficinaEmpleo","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#article","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/"},"author":{"name":"OficinaEmpleo","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114"},"headline":"Diferentes tipos de entrevista de trabajo que te pueden hacer","datePublished":"2016-12-08T23:17:35+00:00","dateModified":"2016-12-09T08:24:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/"},"wordCount":738,"commentCount":0,"publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg","keywords":["entrevista de trabajo","entrevista de trabajo por Skype","preguntas en una entrevista de trabajo","procesos de selecci\u00f3n","selecci\u00f3n de personal","tipos de entrevista de trabajo"],"articleSection":["Recursos humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/","url":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/","name":"Diferentes tipos de entrevista de trabajo que te pueden hacer","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg","datePublished":"2016-12-08T23:17:35+00:00","dateModified":"2016-12-09T08:24:12+00:00","description":"\u00bfTienes una entrevista de trabajo? \u00bfNo sabes a lo que te vas a enfrentar? A continuaci\u00f3n te desglosamos los tipos de entrevista que te pueden hacer.","breadcrumb":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#primaryimage","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2016\/12\/entrevista.jpg","width":590,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/www.oficinaempleo.com\/blog\/diferentes-tipos-entrevista-trabajo-te-pueden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oficinaempleo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Diferentes tipos de entrevista de trabajo que te pueden hacer"}]},{"@type":"WebSite","@id":"https:\/\/www.oficinaempleo.com\/blog\/#website","url":"https:\/\/www.oficinaempleo.com\/blog\/","name":"Noticias y Consejos de Empleo | Blog OficinaEmpleo","description":"","publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization","name":"OficinaEmpleo","url":"https:\/\/www.oficinaempleo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","width":478,"height":57,"caption":"OficinaEmpleo"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/OficinaEmpleo"]},{"@type":"Person","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114","name":"OficinaEmpleo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g","caption":"OficinaEmpleo"},"description":"En OficinaEmpleo queremos ayudarte a conseguir trabajo. Por eso, adem\u00e1s de ofrecerte ofertas de empleo en nuestro portal, te ense\u00f1amos las novedades del sector, y consejos para mejorar tu perfil.","sameAs":["http:\/\/www.oficinaempleo.com\/","https:\/\/www.facebook.com\/OficinaEmpleo","https:\/\/x.com\/OficinaEmpleo"],"url":"https:\/\/www.oficinaempleo.com\/blog\/author\/empleo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/16455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/comments?post=16455"}],"version-history":[{"count":0,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/16455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media\/16456"}],"wp:attachment":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media?parent=16455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/categories?post=16455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/tags?post=16455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}