{"id":30135,"date":"2021-09-27T15:39:39","date_gmt":"2021-09-27T14:39:39","guid":{"rendered":"https:\/\/www.oficinaempleo.com\/blog\/?p=30135"},"modified":"2021-09-27T15:39:39","modified_gmt":"2021-09-27T14:39:39","slug":"30-vacantes-de-empleo-en-only-you-hotel","status":"publish","type":"post","link":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/","title":{"rendered":"30 vacantes de empleo en Only You Hotel"},"content":{"rendered":"<p>El Instituto Municipal para la Formaci\u00f3n y El Empleo (IMFE) est\u00e1 gestionando <strong>30 vacantes de empleo para la nueva apertura del restaurante de lujo Only You Hotel.\u00a0<\/strong><\/p>\n<p>La previsi\u00f3n de abrir dicho establecimiento es a <strong>inicios del mes de octubre<\/strong> en la ciudad de <strong>M\u00e1laga<\/strong>.<\/p>\n<p>Si est\u00e1s interesado en formar parte de esta cadena hotelera en el sector de la restauraci\u00f3n, no dudes en consultar todas las ofertas que ofrece la <a href=\"https:\/\/www.onlyyouhotels.com\/conoce-only-you-hotels\/trabaja-con-nosotros\/\" target=\"_blank\" rel=\"noopener\">p\u00e1gina web de Only You Hotel<\/a>.<\/p>\n<h2>Perfiles para las vacantes de empleo en Only You Hotel<\/h2>\n<p>Al tratarse de trabajar para el restaurante del lujo Hotel Only You, IMFE busca todos tipo de perfiles de restauraci\u00f3n:<\/p>\n<ul>\n<li>De <strong>cocina<\/strong>: cocinero, jefes de cocina, ayudante de cocina.<\/li>\n<li>De <strong>sala<\/strong>: jefe de sala, camareros, ayudantes de sala, runners, hostess.<\/li>\n<\/ul>\n<p>Sumado a estos 30 perfiles que buscan para conformar el equipo humano del restaurante, Only You prev\u00e9 contar con <strong>80 profesionales para la gesti\u00f3n integral del hotel.<\/strong><\/p>\n<div id=\"attachment_30138\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-Arti\u0301culo-texto-4.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-30138\" class=\"wp-image-30138 size-full\" src=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-Arti\u0301culo-texto-4.png\" alt=\"vacantes de empleo en Only You Hotel\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-Arti\u0301culo-texto-4.png 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-Arti\u0301culo-texto-4-300x160.png 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/a><p id=\"caption-attachment-30138\" class=\"wp-caption-text\">Only You Hotel busca 30 profesionales en el sector de la restauraci\u00f3n (iStock).<\/p><\/div>\n<h2>La colaboraci\u00f3n con IMFE<\/h2>\n<p>El pasado <strong>mi\u00e9rcoles 22 de septiembre<\/strong>, el equipo de recursos humanos de Only You abri\u00f3 el proceso de selecci\u00f3n. En total, ya han realizado <strong>m\u00e1s de 100 entrevistas individuales<\/strong> en las instalaciones de IMFE, en calle Victoria.<\/p>\n<p><strong>La marca hotelera sigue queriendo colaborar con IMFE para buscar el personal que m\u00e1s se ajuste a sus necesidades.<\/strong> Adem\u00e1s tambi\u00e9n contar\u00e1n con ellos para futuras vacantes que surjan en otros departamentos del hotel como recepci\u00f3n, mantenimiento, pisos, etc.<\/p>\n<p>\u00abLa participaci\u00f3n del IMFE en el proceso de selecci\u00f3n forma parte de la estrategia municipal para <strong>promover el empleo y apoyar a las empresas creadoras de puestos de trabajo<\/strong>. Y en este caso, la puesta en marcha de un hotel de cinco estrellas supone un importante activo que incrementa nuestra oferta, sumando establecimientos hoteleros de primera categor\u00eda que repercuten de muy distintas maneras en la econom\u00eda de la ciudad. Una de ellas, la creaci\u00f3n de empleo directo\u00bb, ha afirmado Lu\u00eds Verde, concejal del \u00c1rea de Fomento del Empleo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Municipal para la Formaci\u00f3n y El Empleo (IMFE) est\u00e1 gestionando 30 vacantes de empleo para la nueva apertura del restaurante de lujo Only You Hotel.\u00a0 La previsi\u00f3n de abrir dicho establecimiento es a inicios del mes de octubre en la ciudad de M\u00e1laga. Si est\u00e1s interesado en formar parte de esta cadena hotelera [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":30137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[691,6540],"tags":[],"class_list":["post-30135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-empleo","category-empleo","cat-691-id","cat-6540-id","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>30 vacantes de empleo en Only You Hotel - Blog OficinaEmpleo<\/title>\n<meta name=\"description\" content=\"\u00bfTienes perfil de restauraci\u00f3n? Puede que te est\u00e9n buscando con motivo de la nueva apertura del restaurante del lujoso Hotel Only You.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30 vacantes de empleo en Only You Hotel - Blog OficinaEmpleo\" \/>\n<meta property=\"og:description\" content=\"\u00bfTienes perfil de restauraci\u00f3n? Puede que te est\u00e9n buscando con motivo de la nueva apertura del restaurante del lujoso Hotel Only You.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias y consejos de empleo | Blog OficinaEmpleo\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-27T14:39:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rosalia Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:site\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosalia Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/\"},\"author\":{\"name\":\"Rosalia Martinez\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/4475a1f1cd525f261855c9e63e0f4457\"},\"headline\":\"30 vacantes de empleo en Only You Hotel\",\"datePublished\":\"2021-09-27T14:39:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/\"},\"wordCount\":367,\"commentCount\":30,\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png\",\"articleSection\":[\"Actualidad\",\"empleo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/\",\"name\":\"30 vacantes de empleo en Only You Hotel - Blog OficinaEmpleo\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png\",\"datePublished\":\"2021-09-27T14:39:39+00:00\",\"description\":\"\u00bfTienes perfil de restauraci\u00f3n? Puede que te est\u00e9n buscando con motivo de la nueva apertura del restaurante del lujoso Hotel Only You.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png\",\"width\":600,\"height\":310,\"caption\":\"Only You Hotel necesita profesionales para su nueva apertura de restaurante en M\u00e1laga (iStock).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oficinaempleo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"30 vacantes de empleo en Only You Hotel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"name\":\"Noticias y Consejos de Empleo | Blog OficinaEmpleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\",\"name\":\"OficinaEmpleo\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"width\":478,\"height\":57,\"caption\":\"OficinaEmpleo\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/OficinaEmpleo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/4475a1f1cd525f261855c9e63e0f4457\",\"name\":\"Rosalia Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9526002577f59f010e69f495e26788220537382743aeea72a2911f202c991525?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9526002577f59f010e69f495e26788220537382743aeea72a2911f202c991525?s=96&d=mm&r=g\",\"caption\":\"Rosalia Martinez\"},\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/author\/rosalia-martinez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"30 vacantes de empleo en Only You Hotel - Blog OficinaEmpleo","description":"\u00bfTienes perfil de restauraci\u00f3n? Puede que te est\u00e9n buscando con motivo de la nueva apertura del restaurante del lujoso Hotel Only You.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/","og_locale":"es_ES","og_type":"article","og_title":"30 vacantes de empleo en Only You Hotel - Blog OficinaEmpleo","og_description":"\u00bfTienes perfil de restauraci\u00f3n? Puede que te est\u00e9n buscando con motivo de la nueva apertura del restaurante del lujoso Hotel Only You.","og_url":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/","og_site_name":"Noticias y consejos de empleo | Blog OficinaEmpleo","article_published_time":"2021-09-27T14:39:39+00:00","og_image":[{"width":600,"height":310,"url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png","type":"image\/png"}],"author":"Rosalia Martinez","twitter_card":"summary_large_image","twitter_creator":"@OficinaEmpleo","twitter_site":"@OficinaEmpleo","twitter_misc":{"Written by":"Rosalia Martinez","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#article","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/"},"author":{"name":"Rosalia Martinez","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/4475a1f1cd525f261855c9e63e0f4457"},"headline":"30 vacantes de empleo en Only You Hotel","datePublished":"2021-09-27T14:39:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/"},"wordCount":367,"commentCount":30,"publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png","articleSection":["Actualidad","empleo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/","url":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/","name":"30 vacantes de empleo en Only You Hotel - Blog OficinaEmpleo","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png","datePublished":"2021-09-27T14:39:39+00:00","description":"\u00bfTienes perfil de restauraci\u00f3n? Puede que te est\u00e9n buscando con motivo de la nueva apertura del restaurante del lujoso Hotel Only You.","breadcrumb":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#primaryimage","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2021\/09\/OE-DESTACADA-8.png","width":600,"height":310,"caption":"Only You Hotel necesita profesionales para su nueva apertura de restaurante en M\u00e1laga (iStock)."},{"@type":"BreadcrumbList","@id":"https:\/\/www.oficinaempleo.com\/blog\/30-vacantes-de-empleo-en-only-you-hotel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oficinaempleo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"30 vacantes de empleo en Only You Hotel"}]},{"@type":"WebSite","@id":"https:\/\/www.oficinaempleo.com\/blog\/#website","url":"https:\/\/www.oficinaempleo.com\/blog\/","name":"Noticias y Consejos de Empleo | Blog OficinaEmpleo","description":"","publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization","name":"OficinaEmpleo","url":"https:\/\/www.oficinaempleo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","width":478,"height":57,"caption":"OficinaEmpleo"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/OficinaEmpleo"]},{"@type":"Person","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/4475a1f1cd525f261855c9e63e0f4457","name":"Rosalia Martinez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9526002577f59f010e69f495e26788220537382743aeea72a2911f202c991525?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9526002577f59f010e69f495e26788220537382743aeea72a2911f202c991525?s=96&d=mm&r=g","caption":"Rosalia Martinez"},"url":"https:\/\/www.oficinaempleo.com\/blog\/author\/rosalia-martinez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/30135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/comments?post=30135"}],"version-history":[{"count":2,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/30135\/revisions"}],"predecessor-version":[{"id":30139,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/30135\/revisions\/30139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media\/30137"}],"wp:attachment":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media?parent=30135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/categories?post=30135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/tags?post=30135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}