{"id":5661,"date":"2015-09-30T10:07:59","date_gmt":"2015-09-30T08:07:59","guid":{"rendered":"http:\/\/www.oficinaempleo.com\/blog\/?p=5661"},"modified":"2016-03-10T10:46:37","modified_gmt":"2016-03-10T08:46:37","slug":"modelos-de-cv-originales-para-descargar","status":"publish","type":"post","link":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/","title":{"rendered":"Modelos de CV muy originales para descargar"},"content":{"rendered":"<div class=\"su-button-center\"><a href=\"https:\/\/jobs.oficinaempleo.com\/registro?origen=ORG-web&#038;utm_source=OE&#038;utm_medium=boton_registro&#038;utm_content=homepage&#038;utm_campaign=organic\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#ec7d0c;border-color:#bd640a;border-radius:10px\" target=\"__blank\"><span style=\"color:#FFFFFF;padding:8px 26px;font-size:20px;line-height:30px;border-color:#f2a455;border-radius:10px;text-shadow:none\"><i class=\"sui sui-arrow-circle-right\" style=\"font-size:20px;color:#FFFFFF\"><\/i> Reg\u00edstrate gratis en OficinaEmpleo<\/span><\/a><\/div><div class=\"su-spacer\" style=\"height:30px\"><\/div>\n<p style=\"text-align: justify;\">No hace falta que te digamos que confeccionar un <strong>curr\u00edculum<\/strong> adecuado a la oferta de trabajo a la que optes es important\u00edsimo a la hora de obtener resultados e ir avanzando en los procesos de selecci\u00f3n. En otras ocasiones te hemos contado trucos para \u2018vender\u2019 tu historia profesional de la mejor manera posible,  adaptar tu formaci\u00f3n y experiencia a las premisas oficiales europeas,  e incluso <a href=\"http:\/\/www.oficinaempleo.com\/blog\/3-plantillas-para-hacer-tu-curriculum-en-ingles\/\" >transformar tu curr\u00edculum al ingl\u00e9s gracias a modelos gratuitos.<\/a><\/p>\n<p style=\"text-align: justify;\">En esta ocasi\u00f3n, desde <strong>OficinaEmpleo<\/strong> queremos facilitarte la tarea de dise\u00f1ar un curriculum vitae original. Si buscas una tarjeta de presentaci\u00f3n llamativa, diferente y que escape a los convencionalismos, en este post te ense\u00f1amos algunos <strong>modelos\u00a0de CV que puedes descargar de forma gratuita y personalizar con tus datos.<\/strong><\/p>\n<p style=\"text-align: justify;\">Si tu fuerte no es el <strong>dise\u00f1o gr\u00e1fico<\/strong> o no tienes tiempo para dedicarte a la elaboraci\u00f3n de tu nuevo cv, toma nota de las originales alternativas que te proponemos. Eso s\u00ed, aseg\u00farate de que el puesto de trabajo y el contexto del proceso de selecci\u00f3n permitan este tipo de licencias creativas.<\/p>\n<p style=\"text-align: justify;\"><strong>1. <a href=\"http:\/\/www.graphicsfuel.com\/wp-content\/uploads\/2011\/01\/resume-psd-template.zip\" >Una propuesta desenfadada, ideal para profesiones relacionadas con el dise\u00f1o y la creaci\u00f3n. Color, gr\u00e1ficos y detalles visuales te ayudar\u00e1n a destacar entre el resto de candidatos<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5664 size-full\" src=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/01.-resume-psd-template-preview.jpg\" alt=\"01.-resume-psd-template-preview\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/01.-resume-psd-template-preview.jpg 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/01.-resume-psd-template-preview-300x160.jpg 300w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/01.-resume-psd-template-preview-280x150.jpg 280w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>2. <a href=\"http:\/\/cvtemplates.s3.amazonaws.com\/Professional-Resume-Template-upload.zip?AWSAccessKeyId=AKIAIRNVKAZ3PGGAENDA&amp;Expires=1433342720&amp;Signature=2lZmgALdB3SuNzovoERJE1aaBzI%3D\" >Minimalismo de tendencia con logos e ilustraciones al m\u00e1s puro estilo \u2018flat design\u2019, tan de moda en este momento<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5665\" src=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/02.-Professional-Resume-Template-upload-1.jpg\" alt=\"02.-Professional-Resume-Template-upload-1\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/02.-Professional-Resume-Template-upload-1.jpg 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/02.-Professional-Resume-Template-upload-1-300x160.jpg 300w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/02.-Professional-Resume-Template-upload-1-280x150.jpg 280w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>3. <a href=\"https:\/\/s3.amazonaws.com\/Templates-for-CV\/Zip-files\/Fitness-Trainer-Resume.zip\" >Si tu \u00e1mbito profesional es el de entrenador personal o monitor de gimnasio, \u00e9ste es tu modelo de curr\u00edculum.<\/a><\/strong> Tambi\u00e9n si quieres a\u00f1adir un toque de humor y desenfado a tu trayectoria y logros.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5666\" src=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/03.-Fitness-Trainer-Resume-upload.jpg\" alt=\"03.-Fitness-Trainer-Resume-upload\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/03.-Fitness-Trainer-Resume-upload.jpg 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/03.-Fitness-Trainer-Resume-upload-300x160.jpg 300w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/03.-Fitness-Trainer-Resume-upload-280x150.jpg 280w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>4. <a href=\"http:\/\/adf.ly\/1C9I5e\" >Con una est\u00e9tica retro y aspecto de documento impreso de otros tiempos, encontrar\u00e1s esta plantilla disponible en 4 alternativas de color diferentes.<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5667\" src=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/04.-Resume.color-version3.jpg\" alt=\"04.-Resume.color-version3\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/04.-Resume.color-version3.jpg 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/04.-Resume.color-version3-300x160.jpg 300w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/04.-Resume.color-version3-280x150.jpg 280w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>5. <a href=\"http:\/\/adf.ly\/1C9KCd\" >Si quieres mostrar qui\u00e9n eres y qu\u00e9 sabes hacer, te proponemos este modelo con diagramas de barras, iconos y gr\u00e1ficos de progreso ideales para cuantificar experiencia y habilidades.<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5668\" src=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/05.jpg\" alt=\"05\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/05.jpg 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/05-300x160.jpg 300w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/05-280x150.jpg 280w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>6. <a href=\"http:\/\/templatesforcv.com\/cv-template\/front-end-web-developer-resume\/\" >Si buscas un trabajo como dise\u00f1ador web o desarrollador inform\u00e1tico<\/a>, la siguiente propuesta te ayudar\u00e1 a empatizar con el reclutador con un dise\u00f1o inspirado en la navegaci\u00f3n de una p\u00e1gina web&#8230; en este caso, \u00a1la tuya propia!<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5671\" src=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/08.-php_web_developer_resume.jpg\" alt=\"08.-php_web_developer_resume\" width=\"590\" height=\"315\" srcset=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/08.-php_web_developer_resume.jpg 590w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/08.-php_web_developer_resume-300x160.jpg 300w, https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/08.-php_web_developer_resume-280x150.jpg 280w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/p>\n<p style=\"text-align: justify;\">Como consejo final, te advertimos que la mayor\u00eda de estos <strong>modelos de CV<\/strong> est\u00e1n disponibles en formato \u00ab.psd\u00bb. Se trata de archivos editados con el programa <strong>Photoshop<\/strong>, dado su alto componente creativo. Sin embargo, no encontrar\u00e1s ning\u00fan problema en el momento de personalizar estos dise\u00f1os con tu informaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La \u00fanica precauci\u00f3n que debes tener es guardar el documento conservando las \u2018capas\u2019 de <strong>Photoshop<\/strong> e importar tambi\u00e9n el archivo ejecutable con las tipograf\u00edas que incluyen algunas de estas plantillas. Luego, con la plantilla abierta, deber\u00e1s posicionarte en las diferentes capas para insertar todos tus datos.<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo, <strong>no olvides incluir el nombre del dise\u00f1ador, \u00fanica premisa para la descarga gratuita de alguno de estos dise\u00f1os.<\/strong> No lo pienses m\u00e1s y \u00a1atr\u00e9vete con un curr\u00edculum \u00fanico y nada convencional!<\/p>\n<div class=\"su-button-center\"><a href=\"https:\/\/jobs.oficinaempleo.com\/registro?origen=ORG-web&#038;utm_source=OE&#038;utm_medium=boton_registro&#038;utm_content=homepage&#038;utm_campaign=organic\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#ec7d0c;border-color:#bd640a;border-radius:10px\" target=\"__blank\"><span style=\"color:#FFFFFF;padding:8px 26px;font-size:20px;line-height:30px;border-color:#f2a455;border-radius:10px;text-shadow:none\"><i class=\"sui sui-arrow-circle-right\" style=\"font-size:20px;color:#FFFFFF\"><\/i> Reg\u00edstrate gratis en OficinaEmpleo<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQuieres preparar un curr\u00edculum original? Te presentamos varios ejemplos<\/p>\n","protected":false},"author":2,"featured_media":5672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[691,12,3,1],"tags":[900,1654,24,1022,1653,25],"class_list":["post-5661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-empleo","category-consejos-y-recursos","category-noticias-empleo","category-sin-categoria","tag-curriculum","tag-descargar","tag-empleo","tag-modelos-de-curriculum","tag-plantillas-de-curriculum","tag-trabajo","cat-691-id","cat-12-id","cat-3-id","cat-1-id","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelos de CV muy originales para descargar - Blog OficinaEmpleo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelos de CV muy originales para descargar - Blog OficinaEmpleo\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres preparar un curr\u00edculum original? Te presentamos varios ejemplos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias y consejos de empleo | Blog OficinaEmpleo\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/OficinaEmpleo\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-30T08:07:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-10T08:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OficinaEmpleo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:site\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"OficinaEmpleo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/\"},\"author\":{\"name\":\"OficinaEmpleo\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114\"},\"headline\":\"Modelos de CV muy originales para descargar\",\"datePublished\":\"2015-09-30T08:07:59+00:00\",\"dateModified\":\"2016-03-10T08:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/\"},\"wordCount\":589,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg\",\"keywords\":[\"curr\u00edculum\",\"descargar\",\"empleo\",\"modelos de curr\u00edculum\",\"plantillas de curr\u00edculum\",\"trabajo\"],\"articleSection\":[\"Actualidad\",\"Consejos y Recursos\",\"Noticias Empleo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/\",\"name\":\"Modelos de CV muy originales para descargar - Blog OficinaEmpleo\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg\",\"datePublished\":\"2015-09-30T08:07:59+00:00\",\"dateModified\":\"2016-03-10T08:46:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg\",\"width\":590,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oficinaempleo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelos de CV muy originales para descargar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"name\":\"Noticias y Consejos de Empleo | Blog OficinaEmpleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\",\"name\":\"OficinaEmpleo\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"width\":478,\"height\":57,\"caption\":\"OficinaEmpleo\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/OficinaEmpleo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114\",\"name\":\"OficinaEmpleo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g\",\"caption\":\"OficinaEmpleo\"},\"description\":\"En OficinaEmpleo queremos ayudarte a conseguir trabajo. Por eso, adem\u00e1s de ofrecerte ofertas de empleo en nuestro portal, te ense\u00f1amos las novedades del sector, y consejos para mejorar tu perfil.\",\"sameAs\":[\"http:\/\/www.oficinaempleo.com\/\",\"https:\/\/www.facebook.com\/OficinaEmpleo\",\"https:\/\/x.com\/OficinaEmpleo\"],\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/author\/empleo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelos de CV muy originales para descargar - Blog OficinaEmpleo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/","og_locale":"es_ES","og_type":"article","og_title":"Modelos de CV muy originales para descargar - Blog OficinaEmpleo","og_description":"\u00bfQuieres preparar un curr\u00edculum original? Te presentamos varios ejemplos","og_url":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/","og_site_name":"Noticias y consejos de empleo | Blog OficinaEmpleo","article_author":"https:\/\/www.facebook.com\/OficinaEmpleo","article_published_time":"2015-09-30T08:07:59+00:00","article_modified_time":"2016-03-10T08:46:37+00:00","og_image":[{"width":590,"height":315,"url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg","type":"image\/jpeg"}],"author":"OficinaEmpleo","twitter_card":"summary_large_image","twitter_creator":"@OficinaEmpleo","twitter_site":"@OficinaEmpleo","twitter_misc":{"Written by":"OficinaEmpleo","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#article","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/"},"author":{"name":"OficinaEmpleo","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114"},"headline":"Modelos de CV muy originales para descargar","datePublished":"2015-09-30T08:07:59+00:00","dateModified":"2016-03-10T08:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/"},"wordCount":589,"commentCount":0,"publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg","keywords":["curr\u00edculum","descargar","empleo","modelos de curr\u00edculum","plantillas de curr\u00edculum","trabajo"],"articleSection":["Actualidad","Consejos y Recursos","Noticias Empleo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/","url":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/","name":"Modelos de CV muy originales para descargar - Blog OficinaEmpleo","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg","datePublished":"2015-09-30T08:07:59+00:00","dateModified":"2016-03-10T08:46:37+00:00","breadcrumb":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#primaryimage","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/06\/curriculum.jpg","width":590,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/www.oficinaempleo.com\/blog\/modelos-de-cv-originales-para-descargar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oficinaempleo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Modelos de CV muy originales para descargar"}]},{"@type":"WebSite","@id":"https:\/\/www.oficinaempleo.com\/blog\/#website","url":"https:\/\/www.oficinaempleo.com\/blog\/","name":"Noticias y Consejos de Empleo | Blog OficinaEmpleo","description":"","publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization","name":"OficinaEmpleo","url":"https:\/\/www.oficinaempleo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","width":478,"height":57,"caption":"OficinaEmpleo"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/OficinaEmpleo"]},{"@type":"Person","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114","name":"OficinaEmpleo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g","caption":"OficinaEmpleo"},"description":"En OficinaEmpleo queremos ayudarte a conseguir trabajo. Por eso, adem\u00e1s de ofrecerte ofertas de empleo en nuestro portal, te ense\u00f1amos las novedades del sector, y consejos para mejorar tu perfil.","sameAs":["http:\/\/www.oficinaempleo.com\/","https:\/\/www.facebook.com\/OficinaEmpleo","https:\/\/x.com\/OficinaEmpleo"],"url":"https:\/\/www.oficinaempleo.com\/blog\/author\/empleo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/5661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/comments?post=5661"}],"version-history":[{"count":0,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/5661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media\/5672"}],"wp:attachment":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media?parent=5661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/categories?post=5661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/tags?post=5661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}