{"id":7604,"date":"2015-09-14T12:30:02","date_gmt":"2015-09-14T10:30:02","guid":{"rendered":"http:\/\/www.oficinaempleo.com\/blog\/?p=7604"},"modified":"2015-09-14T12:30:02","modified_gmt":"2015-09-14T10:30:02","slug":"renault-creara-1-000-nuevos-puestos-de-trabajo","status":"publish","type":"post","link":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/","title":{"rendered":"Renault crear\u00e1 1.000 nuevos puestos de trabajo"},"content":{"rendered":"<div class=\"su-button-center\"><a href=\"https:\/\/jobs.oficinaempleo.com\/registro?origen=ORG-web&#038;utm_source=OE&#038;utm_medium=boton_registro&#038;utm_content=homepage&#038;utm_campaign=organic\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#ec7d0c;border-color:#bd640a;border-radius:10px\" target=\"__blank\"><span style=\"color:#FFFFFF;padding:8px 26px;font-size:20px;line-height:30px;border-color:#f2a455;border-radius:10px;text-shadow:none\"><i class=\"sui sui-arrow-circle-right\" style=\"font-size:20px;color:#FFFFFF\"><\/i> Reg\u00edstrate gratis en OficinaEmpleo<\/span><\/a><\/div><div class=\"su-spacer\" style=\"height:30px\"><\/div>\n<p style=\"text-align: justify;\">La factor\u00eda de <strong>Renault<\/strong> ubicada en Palencia contratar\u00e1 <strong>1.000 nuevos empleados<\/strong> con motivo de la gran\u00a0demanda detectada en el mercado de su primer\u00a0modelo de Crossover, \u00a0el nuevo\u00a0Kadjar. El proceso de selecci\u00f3n de los candidatos comenzar\u00e1 a partir del <strong>21 de Septiembre.<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/1354704753647.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-7607\" src=\"http:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/1354704753647.jpg\" alt=\"Renault incorpora 1.000 nuevos empleados\" width=\"953\" height=\"593\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">De este modo, la factor\u00eda palentina recupera su tercer turno de trabajo, perdido en el a\u00f1o 2011, y la plantilla llegar\u00e1 a superar los 4.100 trabajadores. La <strong>duraci\u00f3n del turno<\/strong> se definir\u00e1 en funci\u00f3n de la demanda del mercado, en principio la compa\u00f1\u00eda asegura\u00a0que antes de finales de a\u00f1o se habr\u00e1n producido m\u00e1s de\u00a06.400 unidades de veh\u00edculos a la semana.<\/p>\n<p style=\"text-align: justify;\">El nuevo crossover de la marca comenz\u00f3 a fabricarse en abril de 2015 en dos turnos, con una producci\u00f3n de 450 unidades de un total de 900 veh\u00edculos diarios. Cinco meses m\u00e1s tarde, se rescata el tercer turno, con lo que se <strong>extender\u00e1 el trabajo diario en la factor\u00eda.<\/strong><\/p>\n<p style=\"text-align: justify;\">Pincha en este<strong> <a href=\"http:\/\/www.oficinaempleo.com\/oferta-empleo\/1-000-nuevos-puestos-de-trabajo-5416645.html\" >enlace<\/a><\/strong>\u00a0y podr\u00e1s\u00a0observar las ofertas de empleo que ofrece la compa\u00f1\u00eda.<\/p>\n<div class=\"su-button-center\"><a href=\"https:\/\/jobs.oficinaempleo.com\/registro?origen=ORG-web&#038;utm_source=OE&#038;utm_medium=boton_registro&#038;utm_content=homepage&#038;utm_campaign=organic\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#ec7d0c;border-color:#bd640a;border-radius:10px\" target=\"__blank\"><span style=\"color:#FFFFFF;padding:8px 26px;font-size:20px;line-height:30px;border-color:#f2a455;border-radius:10px;text-shadow:none\"><i class=\"sui sui-arrow-circle-right\" style=\"font-size:20px;color:#FFFFFF\"><\/i> Reg\u00edstrate gratis en OficinaEmpleo<\/span><\/a><\/div><div class=\"su-spacer\" style=\"height:30px\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con motivo de la gran demanda de su nuevo modelo Kadjar, Renault ha decidido poner en marcha un tercer turno en la factor\u00eda de Palencia a partir del 21 de septiembre.<\/p>\n","protected":false},"author":2,"featured_media":7609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[691,637,1441,3,689,17,8],"tags":[2346,2110,2344,1095,24,622,2342,2349,2348,2347,2332,2343,2345,2206,217,2341,2338,25],"class_list":["post-7604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-empleo","category-empleo-internacional-2","category-empresas","category-noticias-empleo","category-ofertas-empleo-destacadas","category-profesiones","category-tecnologia","tag-1-000","tag-candidatos","tag-compania","tag-empleados","tag-empleo","tag-empleo-internacional","tag-fabrica","tag-fabricacion","tag-incorporacion","tag-nuevos-puestos","tag-ofertas","tag-palencia","tag-planta","tag-puestos","tag-puestos-de-trabajo","tag-renault","tag-seleccion","tag-trabajo","cat-691-id","cat-637-id","cat-1441-id","cat-3-id","cat-689-id","cat-17-id","cat-8-id","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renault crear\u00e1 1.000 nuevos puestos de trabajo - Blog OficinaEmpleo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renault crear\u00e1 1.000 nuevos puestos de trabajo - Blog OficinaEmpleo\" \/>\n<meta property=\"og:description\" content=\"Con motivo de la gran demanda de su nuevo modelo Kadjar, Renault ha decidido poner en marcha un tercer turno en la factor\u00eda de Palencia a partir del 21 de septiembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias y consejos de empleo | Blog OficinaEmpleo\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/OficinaEmpleo\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-14T10:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"OficinaEmpleo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:site\" content=\"@OficinaEmpleo\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"OficinaEmpleo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/\"},\"author\":{\"name\":\"OficinaEmpleo\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114\"},\"headline\":\"Renault crear\u00e1 1.000 nuevos puestos de trabajo\",\"datePublished\":\"2015-09-14T10:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/\"},\"wordCount\":249,\"commentCount\":176,\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg\",\"keywords\":[\"1.000\",\"candidatos\",\"Compa\u00f1\u00eda\",\"empleados\",\"empleo\",\"empleo internacional\",\"F\u00e1brica\",\"Fabricaci\u00f3n\",\"Incorporaci\u00f3n\",\"nuevos puestos\",\"Ofertas\",\"Palencia\",\"Planta\",\"Puestos\",\"puestos de trabajo\",\"Renault\",\"Selecci\u00f3n\",\"trabajo\"],\"articleSection\":[\"Actualidad\",\"Empleo Internacional\",\"Empresas\",\"Noticias Empleo\",\"Ofertas destacadas\",\"Profesiones\",\"Tecnologia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/\",\"name\":\"Renault crear\u00e1 1.000 nuevos puestos de trabajo - Blog OficinaEmpleo\",\"isPartOf\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg\",\"datePublished\":\"2015-09-14T10:30:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg\",\"width\":600,\"height\":310,\"caption\":\"Renault incorporar\u00e1 1.000 nuevos trabajadores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oficinaempleo.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renault crear\u00e1 1.000 nuevos puestos de trabajo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#website\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"name\":\"Noticias y Consejos de Empleo | Blog OficinaEmpleo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#organization\",\"name\":\"OficinaEmpleo\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"contentUrl\":\"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg\",\"width\":478,\"height\":57,\"caption\":\"OficinaEmpleo\"},\"image\":{\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/OficinaEmpleo\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114\",\"name\":\"OficinaEmpleo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g\",\"caption\":\"OficinaEmpleo\"},\"description\":\"En OficinaEmpleo queremos ayudarte a conseguir trabajo. Por eso, adem\u00e1s de ofrecerte ofertas de empleo en nuestro portal, te ense\u00f1amos las novedades del sector, y consejos para mejorar tu perfil.\",\"sameAs\":[\"http:\/\/www.oficinaempleo.com\/\",\"https:\/\/www.facebook.com\/OficinaEmpleo\",\"https:\/\/x.com\/OficinaEmpleo\"],\"url\":\"https:\/\/www.oficinaempleo.com\/blog\/author\/empleo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renault crear\u00e1 1.000 nuevos puestos de trabajo - Blog OficinaEmpleo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/","og_locale":"es_ES","og_type":"article","og_title":"Renault crear\u00e1 1.000 nuevos puestos de trabajo - Blog OficinaEmpleo","og_description":"Con motivo de la gran demanda de su nuevo modelo Kadjar, Renault ha decidido poner en marcha un tercer turno en la factor\u00eda de Palencia a partir del 21 de septiembre.","og_url":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/","og_site_name":"Noticias y consejos de empleo | Blog OficinaEmpleo","article_author":"https:\/\/www.facebook.com\/OficinaEmpleo","article_published_time":"2015-09-14T10:30:02+00:00","og_image":[{"width":600,"height":310,"url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg","type":"image\/jpeg"}],"author":"OficinaEmpleo","twitter_card":"summary_large_image","twitter_creator":"@OficinaEmpleo","twitter_site":"@OficinaEmpleo","twitter_misc":{"Written by":"OficinaEmpleo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#article","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/"},"author":{"name":"OficinaEmpleo","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114"},"headline":"Renault crear\u00e1 1.000 nuevos puestos de trabajo","datePublished":"2015-09-14T10:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/"},"wordCount":249,"commentCount":176,"publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg","keywords":["1.000","candidatos","Compa\u00f1\u00eda","empleados","empleo","empleo internacional","F\u00e1brica","Fabricaci\u00f3n","Incorporaci\u00f3n","nuevos puestos","Ofertas","Palencia","Planta","Puestos","puestos de trabajo","Renault","Selecci\u00f3n","trabajo"],"articleSection":["Actualidad","Empleo Internacional","Empresas","Noticias Empleo","Ofertas destacadas","Profesiones","Tecnologia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/","url":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/","name":"Renault crear\u00e1 1.000 nuevos puestos de trabajo - Blog OficinaEmpleo","isPartOf":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg","datePublished":"2015-09-14T10:30:02+00:00","breadcrumb":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#primaryimage","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2015\/09\/renault-BLOG.jpg","width":600,"height":310,"caption":"Renault incorporar\u00e1 1.000 nuevos trabajadores"},{"@type":"BreadcrumbList","@id":"https:\/\/www.oficinaempleo.com\/blog\/renault-creara-1-000-nuevos-puestos-de-trabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oficinaempleo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Renault crear\u00e1 1.000 nuevos puestos de trabajo"}]},{"@type":"WebSite","@id":"https:\/\/www.oficinaempleo.com\/blog\/#website","url":"https:\/\/www.oficinaempleo.com\/blog\/","name":"Noticias y Consejos de Empleo | Blog OficinaEmpleo","description":"","publisher":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oficinaempleo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.oficinaempleo.com\/blog\/#organization","name":"OficinaEmpleo","url":"https:\/\/www.oficinaempleo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","contentUrl":"https:\/\/www.oficinaempleo.com\/blog\/wp-content\/uploads\/2018\/10\/logo_footer-1.jpg","width":478,"height":57,"caption":"OficinaEmpleo"},"image":{"@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/OficinaEmpleo"]},{"@type":"Person","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/a7f3437f35bd6bd9ad19addae529a114","name":"OficinaEmpleo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.oficinaempleo.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ea822afb14d7439ba3051d652cf8f548fe540f184ce16a2135fc22c9337bd72e?s=96&d=mm&r=g","caption":"OficinaEmpleo"},"description":"En OficinaEmpleo queremos ayudarte a conseguir trabajo. Por eso, adem\u00e1s de ofrecerte ofertas de empleo en nuestro portal, te ense\u00f1amos las novedades del sector, y consejos para mejorar tu perfil.","sameAs":["http:\/\/www.oficinaempleo.com\/","https:\/\/www.facebook.com\/OficinaEmpleo","https:\/\/x.com\/OficinaEmpleo"],"url":"https:\/\/www.oficinaempleo.com\/blog\/author\/empleo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/7604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/comments?post=7604"}],"version-history":[{"count":0,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/posts\/7604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media\/7609"}],"wp:attachment":[{"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/media?parent=7604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/categories?post=7604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oficinaempleo.com\/blog\/wp-json\/wp\/v2\/tags?post=7604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}